{"id":6927,"date":"2026-01-26T09:04:44","date_gmt":"2026-01-26T08:04:44","guid":{"rendered":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/?p=6927"},"modified":"2026-01-26T09:04:44","modified_gmt":"2026-01-26T08:04:44","slug":"ado-den-haag-ajax-3","status":"publish","type":"post","link":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/","title":{"rendered":"ADO Den Haag &#8211; Ajax"},"content":{"rendered":"<h2>Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax.<\/h2>\n<p>Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie. Het was te verwachten dat Ajax al vroeg druk zou gaan zetten en dit leverde dan ook na een kwartier spelen al de 0-1 op. Na een half uur spelen scoorde Danique Tolhoek de 0-2. De ploeg van Sandra van Tol die tot het einde van het seizoen de hoofdtrainer is kreeg best de nodige kansen maar kwamen niet tot scoren. In de slotfase bepaalde oud ADO speelster Dani\u00eblle Noordermeer de eindstand op 0-3. Yuna Sonoda werd uitgeroepen tot powervrouw van de wedstrijd, een verdiende prijs.<br \/>\n<script src=\"https:\/\/www.oypo.nl\/embed-feec390d-8ab4-4235-9cb2-11103a08d193?folderGuid=3C03AFEEFEF67347\" class=\"js--oypo-script\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege &#8230;. <\/p>\n","protected":false},"author":2,"featured_media":6928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voetbal"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"EdW\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Eric de Wit Photography - Sportfotograaf\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ADO Den Haag \u2013 Ajax - Eric de Wit Photography\" \/>\n\t\t<meta property=\"og:description\" content=\"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-26T08:04:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-26T08:04:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ericdwit\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ADO Den Haag \u2013 Ajax - Eric de Wit Photography\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#blogposting\",\"name\":\"ADO Den Haag \\u2013 Ajax - Eric de Wit Photography\",\"headline\":\"ADO Den Haag &#8211; Ajax\",\"author\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/author\\\/ericdewit\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg\",\"width\":1080,\"height\":1080},\"datePublished\":\"2026-01-26T09:04:44+01:00\",\"dateModified\":\"2026-01-26T09:04:44+01:00\",\"inLanguage\":\"nl-NL\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#webpage\"},\"articleSection\":\"Voetbal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/category\\\/voetbal\\\/#listItem\",\"name\":\"Voetbal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/category\\\/voetbal\\\/#listItem\",\"position\":2,\"name\":\"Voetbal\",\"item\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/category\\\/voetbal\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#listItem\",\"name\":\"ADO Den Haag &#8211; Ajax\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#listItem\",\"position\":3,\"name\":\"ADO Den Haag &#8211; Ajax\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/category\\\/voetbal\\\/#listItem\",\"name\":\"Voetbal\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/#person\",\"name\":\"EdW\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/author\\\/ericdewit\\\/#author\",\"url\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/author\\\/ericdewit\\\/\",\"name\":\"EdW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/\",\"name\":\"ADO Den Haag \\u2013 Ajax - Eric de Wit Photography\",\"description\":\"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/author\\\/ericdewit\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/author\\\/ericdewit\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/ado-den-haag-ajax-3\\\/#mainImage\"},\"datePublished\":\"2026-01-26T09:04:44+01:00\",\"dateModified\":\"2026-01-26T09:04:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/#website\",\"url\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/\",\"name\":\"Eric de Wit Photography\",\"description\":\"Sportfotograaf\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ericdewitphotography.nl\\\/sportfoto\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ADO Den Haag \u2013 Ajax - Eric de Wit Photography","description":"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.","canonical_url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#blogposting","name":"ADO Den Haag \u2013 Ajax - Eric de Wit Photography","headline":"ADO Den Haag &#8211; Ajax","author":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/author\/ericdewit\/#author"},"publisher":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg","width":1080,"height":1080},"datePublished":"2026-01-26T09:04:44+01:00","dateModified":"2026-01-26T09:04:44+01:00","inLanguage":"nl-NL","mainEntityOfPage":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#webpage"},"articleSection":"Voetbal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto#listItem","position":1,"name":"Home","item":"https:\/\/www.ericdewitphotography.nl\/sportfoto","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/category\/voetbal\/#listItem","name":"Voetbal"}},{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/category\/voetbal\/#listItem","position":2,"name":"Voetbal","item":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/category\/voetbal\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#listItem","name":"ADO Den Haag &#8211; Ajax"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#listItem","position":3,"name":"ADO Den Haag &#8211; Ajax","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/category\/voetbal\/#listItem","name":"Voetbal"}}]},{"@type":"Person","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/#person","name":"EdW"},{"@type":"Person","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/author\/ericdewit\/#author","url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/author\/ericdewit\/","name":"EdW"},{"@type":"WebPage","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#webpage","url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/","name":"ADO Den Haag \u2013 Ajax - Eric de Wit Photography","description":"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/#website"},"breadcrumb":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/author\/ericdewit\/#author"},"creator":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/author\/ericdewit\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/#mainImage"},"datePublished":"2026-01-26T09:04:44+01:00","dateModified":"2026-01-26T09:04:44+01:00"},{"@type":"WebSite","@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/#website","url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/","name":"Eric de Wit Photography","description":"Sportfotograaf","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/#person"}}]},"og:locale":"nl_NL","og:site_name":"Eric de Wit Photography - Sportfotograaf","og:type":"article","og:title":"ADO Den Haag \u2013 Ajax - Eric de Wit Photography","og:description":"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.","og:url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/ado-den-haag-ajax-3\/","og:image":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg","og:image:secure_url":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg","og:image:width":1080,"og:image:height":1080,"article:published_time":"2026-01-26T08:04:44+00:00","article:modified_time":"2026-01-26T08:04:44+00:00","article:publisher":"https:\/\/www.facebook.com\/ericdwit","twitter:card":"summary","twitter:title":"ADO Den Haag \u2013 Ajax - Eric de Wit Photography","twitter:description":"Hekkensluiter ADO Den Haag Vrouwen ook niet opgewassen tegen koploper Ajax. Toch bood de thuisploeg verdienstelijk tegenstand maar bleef na 90 minuten wel met lege handen achter. De nieuwe aanwinst Yuna Sonoda liet zich aan alle kanten van het veld zien, maakte vele meters en bewees hiermee een goede aanwinst te zijn voor de selectie.","twitter:image":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-content\/uploads\/2026\/01\/2026-01-25-ADO-Den-Haag-Ajax-SPSN-4-5-1.jpg"},"aioseo_meta_data":{"post_id":"6927","title":null,"description":null,"keywords":null,"keyphrases":{"additional":[],"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}}},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-01-26 08:04:44","updated":"2026-01-26 08:16:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/posts\/6927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/comments?post=6927"}],"version-history":[{"count":1,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/posts\/6927\/revisions"}],"predecessor-version":[{"id":6929,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/posts\/6927\/revisions\/6929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/media?parent=6927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/categories?post=6927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ericdewitphotography.nl\/sportfoto\/wp-json\/wp\/v2\/tags?post=6927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}